{"id":75,"date":"2020-08-15T17:55:51","date_gmt":"2020-08-15T15:55:51","guid":{"rendered":"http:\/\/old.en-impedanz.de\/?page_id=75"},"modified":"2023-05-03T13:04:53","modified_gmt":"2023-05-03T11:04:53","slug":"last-und-pruefwiderstaende","status":"publish","type":"page","link":"https:\/\/old.en-impedanz.de\/en\/last-und-pruefwiderstaende\/","title":{"rendered":"Loads and Test Resistors"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"75\" class=\"elementor elementor-75\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39c36599 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"39c36599\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3364b0ce\" data-id=\"3364b0ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d5eb054 elementor-widget elementor-widget-global elementor-global-340 elementor-widget-image\" data-id=\"6d5eb054\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/old.en-impedanz.de\/en\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"134\" src=\"https:\/\/old.en-impedanz.de\/wp-content\/uploads\/2020\/12\/L1.png\" class=\"attachment-full size-full wp-image-332\" alt=\"\" srcset=\"https:\/\/old.en-impedanz.de\/wp-content\/uploads\/2020\/12\/L1.png 400w, https:\/\/old.en-impedanz.de\/wp-content\/uploads\/2020\/12\/L1-300x101.png 300w, https:\/\/old.en-impedanz.de\/wp-content\/uploads\/2020\/12\/L1-396x134.png 396w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-736391b7\" data-id=\"736391b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"theplus-equal-height elementor-element elementor-element-13104904 elementor-nav-menu__align-center elementor-nav-menu--stretch elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-tp-equal-height-loadded=\".elementor-widget\" data-id=\"13104904\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-angle-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;layout&quot;:&quot;horizontal&quot;,&quot;toggle&quot;:&quot;burger&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-overline e--animation-grow\">\n\t\t\t\t<ul id=\"menu-1-13104904\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-63\"><a href=\"https:\/\/old.en-impedanz.de\/en\/\" class=\"elementor-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-62\"><a href=\"https:\/\/old.en-impedanz.de\/en\/produkte\/\" class=\"elementor-item\">Produkte<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-84\"><a href=\"https:\/\/old.en-impedanz.de\/en\/bordnetznachbildungen\/\" class=\"elementor-sub-item\">Bordnetznachbildungen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-83\"><a href=\"https:\/\/old.en-impedanz.de\/en\/hochvolt-lisns\/\" class=\"elementor-sub-item\">Hochvolt LISNs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-82\"><a href=\"https:\/\/old.en-impedanz.de\/en\/last-und-pruefwiderstaende\/\" class=\"elementor-sub-item\">Last- und Pr\u00fcfwiderst\u00e4nde<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-86\"><a href=\"https:\/\/old.en-impedanz.de\/en\/service\/\" class=\"elementor-item\">Service<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-87\"><a href=\"https:\/\/old.en-impedanz.de\/en\/unternehmen\/\" class=\"elementor-item\">Unternehmen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-85\"><a href=\"https:\/\/old.en-impedanz.de\/en\/kontakt\/\" class=\"elementor-item\">Kontakt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3225\"><a href=\"https:\/\/old.en-impedanz.de\/en\/rental-of-system\/\" class=\"elementor-item\">Rental Of System<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3370\"><a href=\"https:\/\/old.en-impedanz.de\/en\/request-data-sheet\/\" class=\"elementor-item\">Request Data Sheet<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-13104904\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-63\"><a href=\"https:\/\/old.en-impedanz.de\/en\/\" class=\"elementor-item\" tabindex=\"-1\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-62\"><a href=\"https:\/\/old.en-impedanz.de\/en\/produkte\/\" class=\"elementor-item\" tabindex=\"-1\">Produkte<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-84\"><a href=\"https:\/\/old.en-impedanz.de\/en\/bordnetznachbildungen\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Bordnetznachbildungen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-83\"><a href=\"https:\/\/old.en-impedanz.de\/en\/hochvolt-lisns\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Hochvolt LISNs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-82\"><a href=\"https:\/\/old.en-impedanz.de\/en\/last-und-pruefwiderstaende\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Last- und Pr\u00fcfwiderst\u00e4nde<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-86\"><a href=\"https:\/\/old.en-impedanz.de\/en\/service\/\" class=\"elementor-item\" tabindex=\"-1\">Service<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-87\"><a href=\"https:\/\/old.en-impedanz.de\/en\/unternehmen\/\" class=\"elementor-item\" tabindex=\"-1\">Unternehmen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-85\"><a href=\"https:\/\/old.en-impedanz.de\/en\/kontakt\/\" class=\"elementor-item\" tabindex=\"-1\">Kontakt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3225\"><a href=\"https:\/\/old.en-impedanz.de\/en\/rental-of-system\/\" class=\"elementor-item\" tabindex=\"-1\">Rental Of System<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3370\"><a href=\"https:\/\/old.en-impedanz.de\/en\/request-data-sheet\/\" class=\"elementor-item\" tabindex=\"-1\">Request Data Sheet<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b888ab5 elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b888ab5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1331fd4\" data-id=\"1331fd4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1513640 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1513640\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-aa3dcbd\" data-id=\"aa3dcbd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-385cc76\" data-id=\"385cc76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a877b3 elementor-widget elementor-widget-heading\" data-id=\"3a877b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Last- und Pr\u00fcfwiderst\u00e4nde<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f5814f elementor-widget elementor-widget-text-editor\" data-id=\"7f5814f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unsere Lasten, Belastungs- und Pr\u00fcfwiderst\u00e4nde der LR- Serie werden zum Entwickeln, Pr\u00fcfen, Testen und unter Dauerbelastung f\u00fcr unterschiedlichste Anwendungen eingesetzt.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-77a87d0\" data-id=\"77a87d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ccba32 elementor-widget elementor-widget-text-editor\" data-id=\"1ccba32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Typische Einsatzgebiete:<\/p><ul><li><span class=\"TextRun SCXW13428754 BCX9\" lang=\"DE-DE\" xml:lang=\"DE-DE\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW13428754 BCX9\">Im Automotivbereich zur Entwicklung und Pr\u00fcfung von Batterien, Kondensatoren und elektrischen Motoren.<\/span><\/span><\/li><li><span class=\"TextRun SCXW194284850 BCX9\" lang=\"DE-DE\" xml:lang=\"DE-DE\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW194284850 BCX9\">Im Industriebereich zur Entwicklung, Pr\u00fcfung und Dauerbelastung von DC-Netzger\u00e4ten, USVs, Generatoren, ein-und dreiphasigen Spannungsquellen und Stromquellen.<\/span><\/span><\/li><li><span class=\"TextRun SCXW177409023 BCX9\" lang=\"DE-DE\" xml:lang=\"DE-DE\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW177409023 BCX9\">Zur thermischen und elektrischen Simulation in Rechen-, Labor-, Regelzentren.<\/span><\/span><\/li><li><span class=\"TextRun SCXW23100989 BCX9\" lang=\"DE-DE\" xml:lang=\"DE-DE\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW23100989 BCX9\">Zum Entladen von Kondensatoren oder Batterien mit gro\u00dfen Str\u00f6men.<\/span><\/span><\/li><li><span class=\"TextRun SCXW194448017 BCX9\" lang=\"DE-DE\" xml:lang=\"DE-DE\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW194448017 BCX9\">Zum\u00a0<\/span><\/span><span class=\"TextRun SCXW194448017 BCX9\" lang=\"DE-DE\" xml:lang=\"DE-DE\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW194448017 BCX9\">Abtesten<\/span><\/span><span class=\"TextRun SCXW194448017 BCX9\" lang=\"DE-DE\" xml:lang=\"DE-DE\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW194448017 BCX9\">\u00a0der elektrischen Eigenschaften unterschiedlichster Komponenten in Laboren.\u00a0<\/span><\/span><span class=\"EOP SCXW194448017 BCX9\" data-ccp-props=\"{\">\u00a0<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c7fae49\" data-id=\"c7fae49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-020b7d1 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"020b7d1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c78bd66\" data-id=\"c78bd66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2de9824\" data-id=\"2de9824\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f13931 elementor-widget elementor-widget-text-editor\" data-id=\"0f13931\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die LR- Serie bieten wir f\u00fcr DC- und AC-Spannungen in ein- und dreiphasiger Ausf\u00fchrung an. Durch unser innovatives Design sind diese f\u00fcr hohe Dauerstr\u00f6me ausgelegt und wei\u00dfen\u202feinen konstanten Ohmwert \u00fcber einen weiten Leistungs- und Temperaturbereich auf. Unsere Lasten bieten wir in verschiedenen Schutz- und Aufstellungsarten sowie f\u00fcr den mobilen Einsatz an. Kontaktieren Sie uns hierzu einfach und wir designen die passende Last f\u00fcr Sie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7cf466b\" data-id=\"7cf466b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f14d38 elementor-widget elementor-widget-text-editor\" data-id=\"2f14d38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><ul><li>F\u00fcr AC- und DC-Spannungen<\/li><li>Hohe Leitungen bei sehr kompakter Bauweise<\/li><li>Designbar nach definierten Widerstandskurven<\/li><li>Konstanter Ohmwert \u00fcber weiten Leistungs- und Temperaturbereich<\/li><li>Verschiedene Schutz- und Aufstellungsarten sowie f\u00fcr den mobilen Einsatz<\/li><li>Fl\u00fcssigkeitsgek\u00fchlt und\/oder Luftgek\u00fchlt<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-9416c07\" data-id=\"9416c07\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b59dca6 elementor-section-full_width elementor-hidden-tablet elementor-hidden-phone elementor-section-height-default elementor-section-height-default\" data-id=\"b59dca6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a113d50\" data-id=\"a113d50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45e6649 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"45e6649\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12d79b1\" data-id=\"12d79b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6cf12e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6cf12e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3811768\" data-id=\"3811768\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-863abba elementor-widget elementor-widget-image\" data-id=\"863abba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/old.en-impedanz.de\/en\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"350\" height=\"118\" src=\"https:\/\/old.en-impedanz.de\/wp-content\/uploads\/2020\/12\/L2.png\" class=\"attachment-large size-large wp-image-381\" alt=\"\" srcset=\"https:\/\/old.en-impedanz.de\/wp-content\/uploads\/2020\/12\/L2.png 350w, https:\/\/old.en-impedanz.de\/wp-content\/uploads\/2020\/12\/L2-300x101.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5aa8f7c elementor-widget elementor-widget-text-editor\" data-id=\"5aa8f7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Enabling Your Measurements<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2f71cf elementor-icon-list--layout-inline elementor-align-center elementor-mobile-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a2f71cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-house-damage\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">EN-Impedanz GmbH<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ro\u0308hrer Weg 8, 71032 Bo\u0308blingen, Deutschland<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:info@old.en-impedanz.de\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mail-bulk\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@old.en-impedanz.de<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-743fe31 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"743fe31\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-72db454\" data-id=\"72db454\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f28ea7e elementor-widget elementor-widget-text-editor\" data-id=\"f28ea7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/old.en-impedanz.de\/impressum\/\"><b>Impressum<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-f46d08e\" data-id=\"f46d08e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6745b6c elementor-widget elementor-widget-text-editor\" data-id=\"6745b6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/old.en-impedanz.de\/kontakt\/\"><b>Karriere<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-9646180\" data-id=\"9646180\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b87fb3 elementor-widget elementor-widget-text-editor\" data-id=\"6b87fb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/old.en-impedanz.de\/datenschutzerklaerung-2\/\"><b>Datenschutzerkl\u00e4rung<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-696bd12\" data-id=\"696bd12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7027ece elementor-widget elementor-widget-text-editor\" data-id=\"7027ece\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/old.en-impedanz.de\/datenschutzerklaerung-2\/\"><b>Nutzungsbedingungen<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-0aa39a2\" data-id=\"0aa39a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-236034b elementor-widget elementor-widget-text-editor\" data-id=\"236034b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/old.en-impedanz.de\/kontakt\/\" rel=\"noopener\">Kontakt<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce2537c elementor-widget elementor-widget-text-editor\" data-id=\"ce2537c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a9 2021 -2023 All Rights Reserved by EN-Impedanz GmbH\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80001ad elementor-widget elementor-widget-tp-smooth-scroll\" data-id=\"80001ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-smooth-scroll.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"plus-smooth-scroll\" data-scroll-type=\"basic\" data-frameRate=\"758\" data-animationTime=\"1600\" data-stepSize=\"100\" data-pulseAlgorithm=\"1\" data-pulseScale=\"4\" data-pulseNormalize=\"1\" data-accelerationDelta=\"50\" data-accelerationMax=\"3\" data-keyboardSupport=\"1\" data-arrowScroll=\"50\" data-touchpadSupport=\"0\" data-fixedBackground=\"1\" data-basicdata=\"{&quot;Browsers&quot;:[&quot;ieWin7&quot;,&quot;chrome&quot;,&quot;firefox&quot;,&quot;safari&quot;]}\"   data-tablet-off=&quot;no&quot; ><script>var smoothAllowedBrowsers = [\"ieWin7\",\"chrome\",\"firefox\",\"safari\"]<\/script><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Last- und Pr\u00fcfwiderst\u00e4nde Unsere Lasten, Belastungs- und Pr\u00fcfwiderst\u00e4nde der LR- Serie werden zum Entwickeln, Pr\u00fcfen, Testen und unter Dauerbelastung f\u00fcr unterschiedlichste Anwendungen eingesetzt.\u00a0 Typische Einsatzgebiete: Im Automotivbereich zur Entwicklung und Pr\u00fcfung von Batterien, Kondensatoren und elektrischen Motoren. Im Industriebereich zur Entwicklung, Pr\u00fcfung und Dauerbelastung von DC-Netzger\u00e4ten, USVs, Generatoren, ein-und dreiphasigen Spannungsquellen und Stromquellen. Zur thermischen [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-75","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/old.en-impedanz.de\/en\/wp-json\/wp\/v2\/pages\/75","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/old.en-impedanz.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/old.en-impedanz.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/old.en-impedanz.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/old.en-impedanz.de\/en\/wp-json\/wp\/v2\/comments?post=75"}],"version-history":[{"count":262,"href":"https:\/\/old.en-impedanz.de\/en\/wp-json\/wp\/v2\/pages\/75\/revisions"}],"predecessor-version":[{"id":3146,"href":"https:\/\/old.en-impedanz.de\/en\/wp-json\/wp\/v2\/pages\/75\/revisions\/3146"}],"wp:attachment":[{"href":"https:\/\/old.en-impedanz.de\/en\/wp-json\/wp\/v2\/media?parent=75"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}